{"id":3136,"date":"2019-05-27T17:43:11","date_gmt":"2019-05-27T17:43:11","guid":{"rendered":"http:\/\/www.obersdorf.at\/feuerwehr\/?p=3136"},"modified":"2019-05-27T17:43:11","modified_gmt":"2019-05-27T17:43:11","slug":"2019-05-26-ehrungen-beim-abschnittsfeuerwehrtag","status":"publish","type":"post","link":"http:\/\/www.obersdorf.at\/feuerwehr\/2019-05-26-ehrungen-beim-abschnittsfeuerwehrtag\/","title":{"rendered":"2019-05-26 &#8211; Ehrungen beim Abschnittsfeuerwehrtag"},"content":{"rendered":"<p>Beim Abschittsfeuerwehrtag am Sonntag in Hochleithen erhielten 2 Kameraden Auszeichnungen. <!--more--><\/p>\n<ul>\n<li><strong>Josef Maier<\/strong> Dank und Anerkennung f\u00fcr 40 Jahre T\u00e4tigkeiten im Feuerwehrwesen<\/li>\n<li><strong>Robert Weitzendorfer<\/strong> erhielt die Verdienstmedaille 2. Klasse in Silber<\/li>\n<\/ul>\n<p>Wir gratulieren recht herzlich!<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Beim Abschittsfeuerwehrtag am Sonntag in Hochleithen erhielten 2 Kameraden Auszeichnungen.<\/p>\n","protected":false},"author":2,"featured_media":3143,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veranstaltung"],"views":1688,"_links":{"self":[{"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/posts\/3136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/comments?post=3136"}],"version-history":[{"count":1,"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/posts\/3136\/revisions"}],"predecessor-version":[{"id":3144,"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/posts\/3136\/revisions\/3144"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/media\/3143"}],"wp:attachment":[{"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/media?parent=3136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/categories?post=3136"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.obersdorf.at\/feuerwehr\/wp-json\/wp\/v2\/tags?post=3136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}